{"id":2742,"date":"2021-11-02T00:00:00","date_gmt":"2021-11-02T00:00:00","guid":{"rendered":"https:\/\/www.isdv.net\/abrechnung-neustarthilfe\/"},"modified":"2022-11-08T20:26:09","modified_gmt":"2022-11-08T20:26:09","slug":"abrechnung-neustarthilfe","status":"publish","type":"post","link":"https:\/\/www.isdv.net\/en\/abrechnung-neustarthilfe\/","title":{"rendered":"ABRECHNUNG NEUSTARTHILFE"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\">F&uuml;r das erste Halbjahr kann die Endabrechnung der Neustarthilfe (1. Halbjahr 2021) durchgef&uuml;hrt werden.<\/p>\n<p>Voraussetzung:<\/p>\n<ol class=\"ProsemirrorEditor-list\">\n<li class=\"ProsemirrorEditor-listItem\" style=\"margin-left: 32px;\" data-list-indent=\"1\" data-list-type=\"numbered\">\n<p>Du hast einen Direktantrag (ohne Steuerberater) auf Neustarthilfe (Monate Januar bis Juni) gestellt.<\/p>\n<\/li>\n<li class=\"ProsemirrorEditor-listItem\" style=\"margin-left: 32px;\" data-list-indent=\"1\" data-list-type=\"numbered\">\n<p>Du hast Geld ausgezahlt bekommen (Antrag wurde stattgegeben)<\/p>\n<\/li>\n<\/ol>\n<p>Unter dem Link:<\/p>\n<p><a class=\"ProsemirrorEditor-link\" href=\"https:\/\/direktantrag.ueberbrueckungshilfe-unternehmen.de\/auth\/realms\/soloselbstaendig\/protocol\/openid-connect\/auth?response_type=code&amp;client_id=antrag-component&amp;redirect_uri=https%3A%2F%2Fdirektantrag.ueberbrueckungshilfe-unternehmen.de%2Fantrag%2Fsso%2Flogin&amp;state=804df6e7-b9b1-4417-ba12-573a1fbd68db&amp;login=true&amp;scope=openid\" target=\"_blank\" rel=\"noopener\">https:\/\/direktantrag.ueberbrueckungshilfe-unternehmen.de\/auth\/realms\/soloselbstaendig\/protocol\/openid-connect\/auth?response_type=code&amp;client_id=antrag-component&amp;redirect_uri=https%3A%2F%2Fdirektantrag.ueberbrueckungshilfe-unternehmen.de%2Fantrag%2Fsso%2Flogin&amp;state=804df6e7-b9b1-4417-ba12-573a1fbd68db&amp;login=true&amp;scope=openid<\/a><\/p>\n<p>kannst Du mit Deinem Elsterzertifikat die Abrechnung durchf&uuml;hren.<\/p>\n<p>Vier Felder m&uuml;ssen ausgef&uuml;llt werden, analog zur Beantragung (tats&auml;chlicher Umsatz, erhaltener Lohnersatz, Eink&uuml;nfte aus abh&auml;ngig Besch&auml;ftigung, Gesamtumsatz 2019) und die Einwilligungserkl&auml;rung muss ausgef&uuml;llt werden (viele H&auml;kchen).<\/p>\n<p>Ob und wieviel Du zur&uuml;ckzahlen musst, sagt Dir das System sofort. Der Bescheid folgt dann auch noch.<\/p>\n<p>Wenn Du dazu noch etwas mehr h&ouml;ren m&ouml;chtest oder auch Deine Erfahrungen mitteilen magst, kannst Du Dich gerne am gemeinsamen Talk des ISDV und VGSD beteiligen.<\/p>\n<p>Dieser Talk findet morgen, 02.11.21 von 16-17:00 Uhr auf der Plattform des VGSD statt.<\/p>\n<p>Hier der Link zur Anmeldung:<\/p>\n<p><a class=\"ProsemirrorEditor-link\" href=\"https:\/\/www.vgsd.de\/event-permalink\/6310\" target=\"_blank\" rel=\"noopener\">https:\/\/www.vgsd.de\/event-permalink\/6310<\/a><\/p>\n<p>&#8222;<\/p>","protected":false},"excerpt":{"rendered":"<p>F&uuml;r das erste Halbjahr kann die Endabrechnung der Neustarthilfe (1. Halbjahr 2021) durchgef&uuml;hrt werden. Voraussetzung: Du hast einen Direktantrag (ohne Steuerberater) auf Neustarthilfe (Monate Januar bis Juni) gestellt. Du hast Geld ausgezahlt bekommen (Antrag wurde stattgegeben) Unter dem Link: https:\/\/direktantrag.ueberbrueckungshilfe-unternehmen.de\/auth\/realms\/soloselbstaendig\/protocol\/openid-connect\/auth?response_type=code&amp;client_id=antrag-component&amp;redirect_uri=https%3A%2F%2Fdirektantrag.ueberbrueckungshilfe-unternehmen.de%2Fantrag%2Fsso%2Flogin&amp;state=804df6e7-b9b1-4417-ba12-573a1fbd68db&amp;login=true&amp;scope=openid kannst Du mit Deinem Elsterzertifikat die Abrechnung durchf&uuml;hren. Vier Felder m&uuml;ssen ausgef&uuml;llt werden, analog zur [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2743,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-2742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selbststaendigkeit"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/posts\/2742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/comments?post=2742"}],"version-history":[{"count":0,"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/posts\/2742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/media\/2743"}],"wp:attachment":[{"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/media?parent=2742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/categories?post=2742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.isdv.net\/en\/wp-json\/wp\/v2\/tags?post=2742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}